{"id":996,"date":"2020-03-29T08:59:37","date_gmt":"2020-03-29T06:59:37","guid":{"rendered":"https:\/\/www.lecokon.fr\/kine\/?p=996"},"modified":"2020-05-17T07:27:23","modified_gmt":"2020-05-17T05:27:23","slug":"kines-envie-de-vous-former-a-distance","status":"publish","type":"post","link":"https:\/\/www.lecokon.fr\/kine\/kines-envie-de-vous-former-a-distance\/","title":{"rendered":"Kin\u00e9s envie de vous former \u00e0 distance ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"996\" class=\"elementor elementor-996\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85be37e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85be37e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b130ff1\" data-id=\"b130ff1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f2815b elementor-widget elementor-widget-heading\" data-id=\"0f2815b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Kin\u00e9s envie de vous former \u00e0 distance ?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25d5bed6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25d5bed6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15573bb3\" data-id=\"15573bb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19f601ec elementor-widget elementor-widget-text-editor\" data-id=\"19f601ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Habituellement, la majorit\u00e9 des kin\u00e9s lib\u00e9raux nous manquons de temps pour <s>tout<\/s> pour se former. Gr\u00e2ce \u00e0 la technologie num\u00e9rique nous pouvons le faire en respectant le confinement ! Voil\u00e0 une s\u00e9lection de podcast, vid\u00e9o et MOOC gratuits pour enrichir vos connaissances<\/p><h3>C\u00f4t\u00e9 coronavirus<\/h3><p>Sur le site de ActuKin\u00e9, gr\u00e2ce au travail de Olivier Daudier, Patrice Piette, Th\u00e9o Lidoreau, vous pouvez trouver un e-learning gratuit sur le <strong>\u00ab\u00a0COVID-19 et Kin\u00e9sith\u00e9rapie\u00a0\u00bb<\/strong>. Un travail valid\u00e9 par la SKR et au CMK et soutenu par la fnek. Merci aux auteurs pour le travail accompli !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15d4b129 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15d4b129\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c5073bf\" data-id=\"5c5073bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e7b3b94 elementor-widget elementor-widget-text-editor\" data-id=\"5e7b3b94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"wp-embed-heading\">E-Learning en acc\u00e8s gratuit : COVID-19 et Kin\u00e9sith\u00e9rapie<\/h4><div class=\"wp-embed-excerpt\"><p>Actukine met \u00e0 votre disposition gratuitement les ressources relatives \u00e0 la prise en charge des patients atteints de covid19. Cette ressource rassemble les recommandations du dispositif du parcours de soins, les recommandations de prises en charge \u00e0 la fois par les soci\u00e9t\u00e9s savantes et la litt\u00e9rature disponible sur le sujet. Merci \u00e0 la SKR et \u2026 <a href=\"https:\/\/www.actukine.com\/e-learning-en-acces-gratuit-covid-19-et-kinesitherapie\/\" target=\"_blank\" rel=\"noopener\">Lire la suite de l&rsquo;article sur Actukin\u00e9<\/a><\/p><h3>C\u00f4t\u00e9 d\u00e9ontologie<\/h3><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-1001\" src=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/moocdeontologie-400x287-1.png\" alt=\"\" width=\"400\" height=\"287\" \/><\/p><p>Le conseil de l\u2019Ordre des Masseurs-Kin\u00e9sith\u00e9rapeutes avait, avant l\u2019\u00e9pid\u00e9mie de coronavirus, pr\u00e9par\u00e9 un mooc sur <strong>\u00ab\u00a0la d\u00e9ontologie, l\u2019affaire de tous\u00a0\u00bb.<\/strong> Il concerne sp\u00e9cifiquement la compr\u00e9hension de la d\u00e9ontologie dans la pratique professionnelle du Masseur-Kin\u00e9sith\u00e9rapeute. Les cours durent sur 5 semaines (+ ou \u2013 que le confinement\u2026l\u2019avenir le dira) avec environ 2H de travail estim\u00e9 par semaine. <strong>Les inscriptions sont actuellement ouvertes avec un d\u00e9but des cours le 31 mars 2020. <\/strong>Je suis inscrite, la suite dans 5\u00a0 semaines\u2026<\/p><p><a href=\"https:\/\/www.pns-mooc.com\/fr\/mooc\/4\/presentation\">https:\/\/www.pns-mooc.com\/fr\/mooc\/4\/presentation<\/a><\/p><h3>C\u00f4t\u00e9 sport<\/h3><p>Une conf\u00e9rence r\u00e9alis\u00e9e par Samuel Marcora sur <strong>\u00ab\u00a0Running fatigue: and the brain?\u00a0\u00bb<\/strong> et publi\u00e9e par SportFisio l\u2019association suisse de physioth\u00e9rapie du sport ASPS. A r\u00e9server aux anglophones.<\/p><p><img decoding=\"async\" class=\"alignleft size-full wp-image-1010\" src=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/fun-1-400x243-1.png\" alt=\"\" width=\"400\" height=\"243\" \/>Pour les moocs, France Universit\u00e9 Num\u00e9rique nous offre <strong>un beau cadeau en r\u00e9-ouvrant les moocs archiv\u00e9s.<\/strong> Le mode \u00ab\u00a0archiv\u00e9 ouvert\u00a0\u00bb vous permet de suivre le cours dans son entier, la seule diff\u00e9rence c\u2019est que vous n\u2019avez pas acc\u00e8s \u00e0 un forum ni \u00e0 un accompagnement. Mais cela ne nous emp\u00eache pas de profiter des nombreuses p\u00e9pites que contient FUN !<\/p><p>\u00a0<\/p><\/div><p><img decoding=\"async\" class=\"alignleft size-full wp-image-1011\" src=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/Screenshot_2020-03-28-entra\u00eenement-sportif-en-trail-et-ultra-trail-2-0-400x226-1.png\" alt=\"\" width=\"400\" height=\"226\" \/><\/p><p>Un mooc sur <strong>\u00ab\u00a0L\u2019entra\u00eenement sportif en trail et ultra-trail 2.0 \u00ab\u00a0<\/strong>. Temps de travail estim\u00e9 3H\/semaine sur 6 semaines initialement<\/p><p><a href=\"https:\/\/www.fun-mooc.fr\/courses\/course-v1:univ-toulouse+61003+session04\/about\">https:\/\/www.fun-mooc.fr\/courses\/course-v1:univ-toulouse+61003+session04\/about<\/a><\/p><hr class=\"wp-block-separator is-style-dots\" \/><div class=\"wp-block-spacer\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1013\" src=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/Screenshot_2020-03-28-Le-mouvement-humain-session-1-400x226-1.png\" alt=\"\" width=\"400\" height=\"226\" \/><\/div><p>\u00a0<\/p><p>Un mooc sur <strong>\u00ab\u00a0le mouvement humain\u00a0\u00bb<\/strong> Temps de travail estim\u00e9 2H\/semaine sur 5 semaines initialement. <a href=\"https:\/\/www.fun-mooc.fr\/courses\/course-v1:univnantes+31007+session01\/about\">https:\/\/www.fun-mooc.fr\/courses\/course-v1:univnantes+31007+session01\/about<\/a><\/p><p>Un mooc sur un aspect moins classiquement abord\u00e9 en kin\u00e9sith\u00e9rapie : <strong>\u00ab\u00a0Dopage : Sports, Organisations et Sciences\u00a0\u00bb <\/strong><a href=\"https:\/\/www.my-mooc.com\/fr\/mooc\/dopage-sports-organisations-et-sciences\/\">https:\/\/www.my-mooc.com\/fr\/mooc\/dopage-sports-organisations-et-sciences\/\u00a0<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6334f04a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6334f04a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afb160c\" data-id=\"afb160c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49b522ef elementor-widget elementor-widget-spacer\" data-id=\"49b522ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-848ed51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"848ed51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d733ce8\" data-id=\"2d733ce8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29729617 elementor-widget elementor-widget-text-editor\" data-id=\"29729617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>C\u00f4t\u00e9 pathologie<\/h3><p>Un mooc de FUN en archiv\u00e9 ouvert sur <strong>la maladie de Parkinson avec un niveau sp\u00e9cial professionnel de sant\u00e9 : <\/strong><a href=\"https:\/\/www.fun-mooc.fr\/courses\/course-v1:univnantes+31008+session01\/about\">https:\/\/www.fun-mooc.fr\/courses\/course-v1:univnantes+31008+session01\/about<\/a><\/p><p>Un mooc de FUN sur <strong>l\u2019asthme de l\u2019adulte<\/strong> mais dont les cours d\u00e9marrent le 20 avril 2020 avec une fin des inscriptions le 31 mai : <a href=\"https:\/\/www.fun-mooc.fr\/courses\/course-v1:CNAM+01045+session02\/about\">https:\/\/www.fun-mooc.fr\/courses\/course-v1:CNAM+01045+session02\/about <\/a><\/p><div class=\"wp-block-spacer\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1016 aligncenter\" src=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/Screenshot_2020-03-28-Asthme-de-ladulte-400x223-1.png\" alt=\"\" width=\"400\" height=\"223\" \/><\/div><h3>C\u00f4t\u00e9 protection du patient<\/h3><p><strong>PNS (P\u00e9dagogie Num\u00e9rique en Sant\u00e9)<\/strong> qui h\u00e9berge le mooc en d\u00e9ontologie du conseil de l\u2019Ordre propose aussi dans ses archives un mooc sur<strong> \u00ab\u00a0les violences faites aux femmes\u00a0\u00bb<\/strong> et un autre sur <strong>\u00ab\u00a0agir contre les maltraitances vis-\u00e0-vis des enfants : l\u2019affaire de tous\u00a0\u00bb<\/strong><\/p><p><a href=\"https:\/\/www.pns-mooc.com\/fr\/\">https:\/\/www.pns-mooc.com\/fr\/<\/a><\/p><p>Une ressource bonus qui n\u2019est pas un mooc mais un <strong>podcast<\/strong> : l\u2019\u00e9mission de Vincent et Marie<strong> \u00ab\u00a0le temps d\u2019un lapin\u00a0\u00bb<\/strong> sur <strong>le coping<\/strong> avec Yvan Sonjon pour y trouver des ressources pour nous aider et \u00e9ventuellement aider nos patients \u00e0 supporter le confinement : <\/p><p><a href=\"https:\/\/soundcloud.com\/lapin-letempsdunlapin\/confinement-le-coping-du-lapin\" target=\"_blank\" rel=\"noopener\">https:\/\/soundcloud.com\/lapin-letempsdunlapin\/confinement-le-coping-du-lapin<\/a><\/p><h4>Et pour finir une le\u00e7on d\u2019anatomie adapt\u00e9e au confinement :<\/h4><p><span class=\"gmail_default\">\u200b<\/span><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1021\" src=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/Screenshot_2020-03-28-Jean-Vivi\u00e8s-sur-Twitter-La-le\u00e7on-danatomie-de-Rembrandt-version-visio-conf\u00e9rence-https-t-co-PVrI4T8....png\" alt=\"\" width=\"748\" height=\"926\" srcset=\"https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/Screenshot_2020-03-28-Jean-Vivi\u00e8s-sur-Twitter-La-le\u00e7on-danatomie-de-Rembrandt-version-visio-conf\u00e9rence-https-t-co-PVrI4T8....png 748w, https:\/\/www.lecokon.fr\/kine\/wp-content\/uploads\/Screenshot_2020-03-28-Jean-Vivi\u00e8s-sur-Twitter-La-le\u00e7on-danatomie-de-Rembrandt-version-visio-conf\u00e9rence-https-t-co-PVrI4T8...-485x600.png 485w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/p><p>Enfin, quand vous ne serez pas sur votre ordinateur en train de suivre un mooc, Gildas Ribot (@Giribot sur Twitter) vous sugg\u00e8re <strong>une utilisation pour aider la science dans le cadre de l\u2019\u00e9pid\u00e9mie de coronavirus avec le projet \u00ab\u00a0Folding at home\u00a0\u00bb : <\/strong><br \/>\u00ab\u00a0Peut on aider \u00e0 arr\u00eater l\u2019\u00e9pid\u00e9mie de covid19 en \u00e9tant confin\u00e9 chez soi ?<br \/>Oui ! <strong>Donner du temps de calcul inutilis\u00e9 de votre pc<\/strong> \u00e0 la science au projet \u00abFolding at home\u00bb pour calculer un anticorps qui marche. Plus d\u2019infos ici:<br \/><a href=\"https:\/\/t.co\/mdbUxNr83W\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/t.co\/mdbUxNr83W<\/a> \u00ab<\/p><p><strong>Prenez soin de vous et de vos proches !<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kin\u00e9s envie de vous former \u00e0 distance ? Habituellement, la majorit\u00e9 des kin\u00e9s lib\u00e9raux nous manquons de temps pour tout pour se former. Gr\u00e2ce \u00e0 la technologie num\u00e9rique nous pouvons le faire en respectant le confinement ! Voil\u00e0 une s\u00e9lection de podcast, vid\u00e9o et MOOC gratuits pour enrichir vos connaissances C\u00f4t\u00e9 coronavirus Sur le site [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"left-sidebar","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[27],"tags":[],"class_list":["post-996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-former","entry","has-media"],"_links":{"self":[{"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/posts\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":25,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"predecessor-version":[{"id":1056,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/posts\/996\/revisions\/1056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/media\/997"}],"wp:attachment":[{"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lecokon.fr\/kine\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}